{"id":1750,"date":"2020-03-12T18:15:07","date_gmt":"2020-03-12T18:15:07","guid":{"rendered":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/what-is-the-difference-between-acting-as-a-leader-rather-than-as-an-individual-contributor-2\/"},"modified":"2026-03-12T21:31:06","modified_gmt":"2026-03-12T21:31:06","slug":"1750","status":"publish","type":"post","link":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/1750\/","title":{"rendered":"<a href=https:\/\/www.linkedin.com\/feed\/update\/urn%3Ali%3Ashare%3A6643932335572164609><\/a>"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1750","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/comments?post=1750"}],"version-history":[{"count":7,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1750\/revisions"}],"predecessor-version":[{"id":5445,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1750\/revisions\/5445"}],"wp:attachment":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/media?parent=1750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/categories?post=1750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/tags?post=1750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}