{"id":1675,"date":"2020-11-11T18:18:01","date_gmt":"2020-11-11T18:18:01","guid":{"rendered":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/when-do-you-actively-create-rather-than-passively-consume-2\/"},"modified":"2026-03-12T21:30:50","modified_gmt":"2026-03-12T21:30:50","slug":"1675","status":"publish","type":"post","link":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/1675\/","title":{"rendered":"<a href=https:\/\/www.linkedin.com\/feed\/update\/urn%3Ali%3Ashare%3A6732355706290339840><\/a>"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1675","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/comments?post=1675"}],"version-history":[{"count":7,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1675\/revisions"}],"predecessor-version":[{"id":5368,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1675\/revisions\/5368"}],"wp:attachment":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/media?parent=1675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/categories?post=1675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/tags?post=1675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}