{"id":1503,"date":"2022-04-23T15:17:36","date_gmt":"2022-04-23T15:17:36","guid":{"rendered":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/oof-wanting-doesnt-equal-willing-2\/"},"modified":"2026-03-12T21:30:25","modified_gmt":"2026-03-12T21:30:25","slug":"1503","status":"publish","type":"post","link":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/1503\/","title":{"rendered":"<a href=https:\/\/www.linkedin.com\/feed\/update\/urn%3Ali%3Ashare%3A6923651094015340544><\/a>"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1503","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/comments?post=1503"}],"version-history":[{"count":7,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1503\/revisions"}],"predecessor-version":[{"id":5198,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1503\/revisions\/5198"}],"wp:attachment":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/media?parent=1503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/categories?post=1503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/tags?post=1503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}