{"id":1411,"date":"2023-02-08T04:35:35","date_gmt":"2023-02-08T04:35:35","guid":{"rendered":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/ive-been-a-fan-of-lolita-taub-for-years-and-am-excited-about-what-shes-doing-with-ganas-ventures-disclosure-im-an-lp\/"},"modified":"2026-03-12T21:30:07","modified_gmt":"2026-03-12T21:30:07","slug":"1411","status":"publish","type":"post","link":"https:\/\/nehrlich.com\/linkedin\/uncategorized\/1411\/","title":{"rendered":"<a href=https:\/\/www.linkedin.com\/feed\/update\/urn%3Ali%3Ashare%3A7028944396536467456><\/a>"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1411","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":2,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"predecessor-version":[{"id":5109,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/posts\/1411\/revisions\/5109"}],"wp:attachment":[{"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nehrlich.com\/linkedin\/wp-json\/wp\/v2\/tags?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}